{"id":4239,"date":"2026-05-25T13:51:40","date_gmt":"2026-05-25T06:51:40","guid":{"rendered":"https:\/\/www.ananeabeyondkhaolak.com\/kol-review\/ploylee-diary\/"},"modified":"2026-06-04T15:06:03","modified_gmt":"2026-06-04T08:06:03","slug":"ploylee-diary","status":"publish","type":"reviews-sub","link":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/kol-review\/ploylee-diary\/","title":{"rendered":"Ploylee diary"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"<p>\u0e1a\u0e35\u0e22\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e02\u0e32\u0e2b\u0e25\u0e31\u0e01 \u0e04\u0e37\u0e2d \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e2a\u0e38\u0e14\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a \u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e23\u0e32\u0e22\u0e25\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e0a\u0e2d\u0e38\u0e48\u0e21<\/p>\n","protected":false},"featured_media":4240,"template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-4239","reviews-sub","type-reviews-sub","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ploylee diary - Ananea Beyond Khaolak<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"th_TH\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ploylee diary - Ananea Beyond Khaolak\" \/>\n<meta property=\"og:description\" content=\"\u0e1a\u0e35\u0e22\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e02\u0e32\u0e2b\u0e25\u0e31\u0e01 \u0e04\u0e37\u0e2d \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e2a\u0e38\u0e14\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a \u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e23\u0e32\u0e22\u0e25\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e0a\u0e2d\u0e38\u0e48\u0e21\" \/>\n<meta property=\"og:url\" content=\"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/kol-review\/ploylee-diary\/\" \/>\n<meta property=\"og:site_name\" content=\"Ananea Beyond Khaolak\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/ananeaBeyondKhaolak\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-04T08:06:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.ananeabeyondkhaolak.com\/wp-content\/uploads\/2026\/05\/blog-3-1.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"675\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 \u0e19\u0e32\u0e17\u0e35\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/kol-review\\\/ploylee-diary\\\/\",\"url\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/kol-review\\\/ploylee-diary\\\/\",\"name\":\"Ploylee diary - Ananea Beyond Khaolak\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/kol-review\\\/ploylee-diary\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/kol-review\\\/ploylee-diary\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/blog-3-1.webp\",\"datePublished\":\"2026-05-25T06:51:40+00:00\",\"dateModified\":\"2026-06-04T08:06:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/kol-review\\\/ploylee-diary\\\/#breadcrumb\"},\"inLanguage\":\"th\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/kol-review\\\/ploylee-diary\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/kol-review\\\/ploylee-diary\\\/#primaryimage\",\"url\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/blog-3-1.webp\",\"contentUrl\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/blog-3-1.webp\",\"width\":1200,\"height\":675},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/kol-review\\\/ploylee-diary\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ploylee diary\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/#website\",\"url\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/\",\"name\":\"Ananea Beyond Khaolak\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"th\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/#organization\",\"name\":\"Ananea Beyond Khaolak\",\"url\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"th\",\"@id\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/ananea.png\",\"contentUrl\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/ananea.png\",\"width\":512,\"height\":512,\"caption\":\"Ananea Beyond Khaolak\"},\"image\":{\"@id\":\"https:\\\/\\\/ananeabeyondkhaolak.webconnection.app\\\/th\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/ananeaBeyondKhaolak\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ploylee diary - Ananea Beyond Khaolak","robots":{"index":"noindex","follow":"follow"},"og_locale":"th_TH","og_type":"article","og_title":"Ploylee diary - Ananea Beyond Khaolak","og_description":"\u0e1a\u0e35\u0e22\u0e2d\u0e19\u0e14\u0e4c \u0e40\u0e02\u0e32\u0e2b\u0e25\u0e31\u0e01 \u0e04\u0e37\u0e2d \u0e23\u0e35\u0e2a\u0e2d\u0e23\u0e4c\u0e17\u0e1e\u0e31\u0e01\u0e1c\u0e48\u0e2d\u0e19\u0e2a\u0e38\u0e14\u0e2a\u0e21\u0e1a\u0e39\u0e23\u0e13\u0e4c\u0e41\u0e1a\u0e1a \u0e1a\u0e23\u0e23\u0e22\u0e32\u0e01\u0e32\u0e28\u0e2a\u0e27\u0e22\u0e07\u0e32\u0e21 \u0e23\u0e32\u0e22\u0e25\u0e49\u0e2d\u0e21\u0e14\u0e49\u0e27\u0e22\u0e15\u0e49\u0e19\u0e44\u0e21\u0e49\u0e2a\u0e35\u0e40\u0e02\u0e35\u0e22\u0e27\u0e0a\u0e2d\u0e38\u0e48\u0e21","og_url":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/kol-review\/ploylee-diary\/","og_site_name":"Ananea Beyond Khaolak","article_publisher":"https:\/\/www.facebook.com\/ananeaBeyondKhaolak\/","article_modified_time":"2026-06-04T08:06:03+00:00","og_image":[{"width":1200,"height":675,"url":"https:\/\/www.ananeabeyondkhaolak.com\/wp-content\/uploads\/2026\/05\/blog-3-1.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 \u0e19\u0e32\u0e17\u0e35"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/kol-review\/ploylee-diary\/","url":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/kol-review\/ploylee-diary\/","name":"Ploylee diary - Ananea Beyond Khaolak","isPartOf":{"@id":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/#website"},"primaryImageOfPage":{"@id":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/kol-review\/ploylee-diary\/#primaryimage"},"image":{"@id":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/kol-review\/ploylee-diary\/#primaryimage"},"thumbnailUrl":"https:\/\/ananeabeyondkhaolak.webconnection.app\/wp-content\/uploads\/2026\/05\/blog-3-1.webp","datePublished":"2026-05-25T06:51:40+00:00","dateModified":"2026-06-04T08:06:03+00:00","breadcrumb":{"@id":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/kol-review\/ploylee-diary\/#breadcrumb"},"inLanguage":"th","potentialAction":[{"@type":"ReadAction","target":["https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/kol-review\/ploylee-diary\/"]}]},{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/kol-review\/ploylee-diary\/#primaryimage","url":"https:\/\/ananeabeyondkhaolak.webconnection.app\/wp-content\/uploads\/2026\/05\/blog-3-1.webp","contentUrl":"https:\/\/ananeabeyondkhaolak.webconnection.app\/wp-content\/uploads\/2026\/05\/blog-3-1.webp","width":1200,"height":675},{"@type":"BreadcrumbList","@id":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/kol-review\/ploylee-diary\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/"},{"@type":"ListItem","position":2,"name":"Ploylee diary"}]},{"@type":"WebSite","@id":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/#website","url":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/","name":"Ananea Beyond Khaolak","description":"","publisher":{"@id":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"th"},{"@type":"Organization","@id":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/#organization","name":"Ananea Beyond Khaolak","url":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/","logo":{"@type":"ImageObject","inLanguage":"th","@id":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/#\/schema\/logo\/image\/","url":"https:\/\/ananeabeyondkhaolak.webconnection.app\/wp-content\/uploads\/2026\/05\/ananea.png","contentUrl":"https:\/\/ananeabeyondkhaolak.webconnection.app\/wp-content\/uploads\/2026\/05\/ananea.png","width":512,"height":512,"caption":"Ananea Beyond Khaolak"},"image":{"@id":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/ananeaBeyondKhaolak\/"]}]}},"_links":{"self":[{"href":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/wp-json\/wp\/v2\/reviews-sub\/4239","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/wp-json\/wp\/v2\/reviews-sub"}],"about":[{"href":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/wp-json\/wp\/v2\/types\/reviews-sub"}],"version-history":[{"count":1,"href":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/wp-json\/wp\/v2\/reviews-sub\/4239\/revisions"}],"predecessor-version":[{"id":5358,"href":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/wp-json\/wp\/v2\/reviews-sub\/4239\/revisions\/5358"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/wp-json\/wp\/v2\/media\/4240"}],"wp:attachment":[{"href":"https:\/\/ananeabeyondkhaolak.webconnection.app\/th\/wp-json\/wp\/v2\/media?parent=4239"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}